{"id":582,"date":"2025-03-25T07:39:15","date_gmt":"2025-03-25T07:39:15","guid":{"rendered":"https:\/\/lotus.fpmt.org\/event\/in-depth-meditation-course-for-experienced-practitioners-year-2-term-2-february-april-2025-yeshin-norbu-5\/"},"modified":"2025-04-01T08:46:49","modified_gmt":"2025-04-01T08:46:49","slug":"in-depth-meditation-course-for-experienced-practitioners-year-2-term-2-february-april-2025-yeshin-norbu-5","status":"publish","type":"tribe_events","link":"https:\/\/lotus.fpmt.org\/fr\/event\/in-depth-meditation-course-for-experienced-practitioners-year-2-term-2-february-april-2025-yeshin-norbu-5\/","title":{"rendered":"Cours approfondi de m\u00e9ditation pour pratiquants exp\u00e9riment\u00e9s : Ann\u00e9e 2, deuxi\u00e8me trimestre (f\u00e9vrier-avril 2025) \u2013 Yeshin Norbu"},"content":{"rendered":"<p>Cours de m\u00e9ditation approfondie pour pratiquants exp\u00e9riment\u00e9s : Year 2 Term 2 (f\u00e9vrier - avril 2025)Dans un monde qui ignore souvent son importance, l'esprit reste myst\u00e9rieusement au c\u0153ur de ce que nous appelons la vie. Fond\u00e9e par les fr\u00e8res Vasubandhu et Asanga, l'\u00e9cole bouddhiste Yog\u0101c\u0101ra se concentre sur l'esprit en tant que \u2018pr\u00e9curseur de toutes choses\u2019, cr\u00e9ateur de notre exp\u00e9rience et conteur de notre existence. L'analyse du Yog\u0101c\u0101ra sur la fa\u00e7on dont l'esprit construit notre r\u00e9alit\u00e9 peut nous aider \u00e0 nous lib\u00e9rer des contraintes de l'ego, des sch\u00e9mas habituels et des \u00e9motions r\u00e9actives, afin de faire l'exp\u00e9rience d'une plus grande aisance, de possibilit\u00e9s et d'une plus grande libert\u00e9 \u00e0 chaque instant.<br \/>\nAu cours de la deuxi\u00e8me ann\u00e9e de l'IDMT, nous mettrons l'accent sur l'exp\u00e9rience v\u00e9cue de la m\u00e9ditation, \u00e0 la fois sur le coussin et en dehors. Guid\u00e9s par le troisi\u00e8me tour de roue du Dharma du Bouddha, nous commencerons par nous entra\u00eener aux \u00e9tapes successives de shamatha, suivies d'un voyage plus approfondi dans la m\u00e9ditation de la compr\u00e9hension. Nous explorerons \u00e9galement comment les concepts peuvent nous aveugler et nous ali\u00e9ner en ajoutant une couche imaginaire \u00e0 notre monde interd\u00e9pendant. En utilisant des mod\u00e8les de d\u00e9veloppement spirituel tels que les 37 facteurs d'\u00e9veil et les 10 perfections, nous apprendrons \u00e0 vivre plus librement dans la vie quotidienne. Nous explorerons \u00e9galement le r\u00f4le des r\u00e9cits, la philosophie du langage et la mani\u00e8re de cultiver une grande compassion pour tous les \u00eatres vivants afin de contribuer \u00e0 la gu\u00e9rison de notre monde conflictuel.<br \/>\nLe v\u00e9n\u00e9rable Losang Gendun a consacr\u00e9 pr\u00e8s de quatre d\u00e9cennies \u00e0 la pratique du bouddhisme et a servi en tant que bhikshu (moine bouddhiste) dans la tradition tib\u00e9taine au cours des 18 derni\u00e8res ann\u00e9es. Avant son ordination, il a travaill\u00e9 dans divers domaines tels que les soins palliatifs, la technologie, les organisations de r\u00e9fugi\u00e9s et la gestion commerciale. Sa formation approfondie comprend dix ann\u00e9es d'\u00e9tude de la philosophie et de la pratique bouddhistes dans des monast\u00e8res en France, en Inde, au N\u00e9pal et au Myanmar. En outre, il a pass\u00e9 plus de quatre ans en retraite, s'immergeant dans le sutra et le tantra tib\u00e9tains, ainsi que dans la tradition foresti\u00e8re Theravada birmane. Au cours des 15 derni\u00e8res ann\u00e9es, V\u00e9n. Gendun a \u00e9t\u00e9 un enseignant d\u00e9vou\u00e9, partageant sa connaissance de la philosophie bouddhiste, de la psychologie et de la m\u00e9ditation dans le monde entier. Il r\u00e9pond aux aspirations de Sa Saintet\u00e9 le Dala\u00ef Lama et de Lama Zopa Rinpoch\u00e9 dans le cadre de la FPMT (Fondation pour la pr\u00e9servation de la tradition mahayana). V\u00e9n. Gendun est \u00e9galement membre de Mind &amp; Life Europe, un laboratoire multidisciplinaire qui r\u00e9unit des chercheurs et des praticiens contemplatifs pour explorer la nature de l'exp\u00e9rience. Au-del\u00e0 de ses affiliations bouddhistes, le v\u00e9n\u00e9rable Gendun est chanoine interreligieux \u00e0 la cath\u00e9drale de la paix de Tbilissi, en G\u00e9orgie, et se sent chez lui dans une dargah soufie Mevlavi \u00e0 Istanbul. En 2023, il a fond\u00e9 The Buddha Project, qui s'occupe de l'accompagnement \u00e0 long terme des m\u00e9ditants bouddhistes, de la recherche scientifique, des projets artistiques et de l'engagement social intercontemplatif.<br \/>\nLe projet Buddha<br \/>\nCe cours de m\u00e9ditation fait partie du Buddha Project dirig\u00e9 par le V\u00e9n\u00e9rable Losang Gendun, dont une branche est le Buddha Research Project, une collaboration permanente entre des contemplatifs bouddhistes et des chercheurs scientifiques des universit\u00e9s de N\u00eemes et de Lausanne, et l'organisation Mind &amp; Life (fond\u00e9e par le neuroscientifique Francesco Varela en collaboration avec S.A. le Dala\u00ef Lama). Il vise \u00e0 \u00e9tudier les processus de transformation chez les m\u00e9ditants de longue dur\u00e9e, dans des domaines tels que la sant\u00e9 mentale, la perception et le d\u00e9passement de soi. Un prix europ\u00e9en Varela a \u00e9t\u00e9 d\u00e9cern\u00e9 pour la recherche initiale.<br \/>\nIntroduction de la formation IDMT<br \/>\nLa m\u00e9ditation est essentielle \u00e0 la transformation personnelle et constitue un compl\u00e9ment crucial aux \u00e9tudes bouddhistes. Ce cours en ligne de 4 ans offre aux \u00e9tudiants un soutien approfondi et \u00e0 long terme dans leur d\u00e9veloppement m\u00e9ditatif. Ce cours hebdomadaire propose :<br \/>\nDes instructions traditionnelles authentiques, dans un langage contemporain, visant \u00e0 fournir un ensemble complet d'outils de m\u00e9ditation permettant aux \u00e9tudiants de transformer leur connaissance du Dharma en exp\u00e9rience personnelle.<br \/>\nTh\u00e9ories traditionnelles et modernes sur des sujets compl\u00e9mentaires tels que les mod\u00e8les de d\u00e9veloppement psychologique et spirituel sain, le rituel, la narration, l'\u00e9thique et l'engagement social.<br \/>\nUne communaut\u00e9 internationale de m\u00e9ditants, en ligne et en direct.<br \/>\nPour compl\u00e9ter le cours de l'IDMT, nous proposons \u00e9galement :<br \/>\nRetraites de m\u00e9ditation - retraites d'une semaine et d'un week-end sur vipassana, la compassion et mahamudra, propos\u00e9es dans les centres et en ligne.<br \/>\nYogi Bootcamp - une formation intensive et guid\u00e9e \u00e0 la m\u00e9ditation d'une dur\u00e9e d'un an avec des entretiens personnels hebdomadaires (appel) pour un petit groupe d'\u00e9tudiants internationaux.<br \/>\nJourn\u00e9es de pratique guid\u00e9es par V\u00e9n. Gendun et des \u00e9tudiants exp\u00e9riment\u00e9s de V\u00e9n. Gendun<br \/>\nS\u00e9ances de r\u00e9flexion hebdomadaires, anim\u00e9es par des \u00e9tudiants exp\u00e9riment\u00e9s<br \/>\nWeek-ends avec la possibilit\u00e9 de recevoir les v\u0153ux de refuge \/ la\u00efc (8-9 f\u00e9vrier), les v\u0153ux d'aspirant bodhisattva (14-15 juin) et les v\u0153ux d'engagement bodhisattva (8-9 novembre).<br \/>\nPour plus d'informations sur le contenu du cours, t\u00e9l\u00e9chargez la description du cours (PDF) ici.<br \/>\nCe cours est une collaboration entre 5 centres bouddhistes de la FPMT : Shantideva Center New York (US), Jamyang Buddhist Centre Leeds (UK), Institut Vajrayogini \u00e0 Marzens (FR), Yeshin Norbu Stockholm (SW) et Maitreya Instituut (NL) et par cons\u00e9quent le cours sera suivi par un groupe international de pratiquants bouddhistes.<br \/>\nSi vous vous inscrivez plus tard dans le cours, il est possible de demander l'acc\u00e8s aux enregistrements des cours pr\u00e9c\u00e9dents.<br \/>\nD\u00e9tails pratiques<br \/>\nLa formation \u00e0 la m\u00e9ditation approfondie se d\u00e9roulera chaque semaine le samedi et comprendra environ une heure de m\u00e9ditation guid\u00e9e et une heure et demie d'enseignement. Le cours offre une grande opportunit\u00e9 pour les pratiquants bouddhistes. Au cours de la premi\u00e8re ann\u00e9e, de nombreux sujets fondamentaux seront introduits, mais une compr\u00e9hension de base du bouddhisme mahayana est un pr\u00e9requis pour y participer. Le cours sera donn\u00e9 en anglais, avec une traduction en fran\u00e7ais, en ligne via Zoom. Les enregistrements seront disponibles apr\u00e8s les sessions.<br \/>\nInformations pratiques et modalit\u00e9s d'inscription :<br \/>\nDates des cours : 1 f\u00e9vrier - 12 avril<br \/>\nJour de la semaine : Samedi<br \/>\nHeure : 15:30-18:00 fuseau horaire du centre de l'Europe<br \/>\nLangue : anglais<br \/>\nLieu : En ligne (le lien de zoom sera envoy\u00e9 apr\u00e8s l'inscription)<br \/>\nDonation : entr\u00e9e libre 250 SEK, mensuelle 800 SEK, \u00e0 terme 2000 SEK<br \/>\nDernier jour d'inscription : vous pouvez vous inscrire \u00e0 tout moment<br \/>\nVous vous inscrivez \u00e0 la s\u00e9ance d'information en achetant un billet sur le site web, voir \u201cBillets\u201d ci-dessous.<\/p>","protected":false},"excerpt":{"rendered":"<p>Au cours de la deuxi\u00e8me ann\u00e9e de l'IDMT, nous mettrons l'accent sur l'exp\u00e9rience v\u00e9cue de la m\u00e9ditation, \u00e0 la fois sur le coussin et en dehors.<\/p>","protected":false},"author":2,"featured_media":497,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[4,5],"class_list":["post-582","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-buddhism","tribe_events_cat-meditation","cat_buddhism","cat_meditation"],"_links":{"self":[{"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/tribe_events\/582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":1,"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/tribe_events\/582\/revisions"}],"predecessor-version":[{"id":1039,"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/tribe_events\/582\/revisions\/1039"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/media\/497"}],"wp:attachment":[{"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/media?parent=582"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/tags?post=582"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/tribe_events_cat?post=582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}