{"id":543,"date":"2025-03-25T07:38:30","date_gmt":"2025-03-25T07:38:30","guid":{"rendered":"https:\/\/lotus.fpmt.org\/event\/medicine-buddha-practice-and-puja-yeshin-norbu\/"},"modified":"2025-04-06T10:14:59","modified_gmt":"2025-04-06T10:14:59","slug":"medicine-buddha-practice-and-puja-yeshin-norbu","status":"publish","type":"tribe_events","link":"https:\/\/lotus.fpmt.org\/fr\/event\/medicine-buddha-practice-and-puja-yeshin-norbu\/","title":{"rendered":"Pratique et Puja du Bouddha de M\u00e9decine - Yeshin Norbu"},"content":{"rendered":"<p>Pratique et Puja du Bouddha de la m\u00e9decinePuja du Bouddha de la m\u00e9decine<br \/>\nRejoignez-nous pour la Puja du Bouddha de la m\u00e9decine, un excellent moyen de promouvoir la gu\u00e9rison pour nous-m\u00eames et pour les autres. Cette pratique s'inscrit dans le cadre des 15 jours de miracles, ce qui est particuli\u00e8rement b\u00e9n\u00e9fique pour la pratique m\u00e9ritoire.<br \/>\n\u00c0 propos de cet \u00e9v\u00e9nement<br \/>\nNous pratiquons ensemble le Bouddha de m\u00e9decine, sous la direction du V\u00e9n\u00e9rable Khadro. Les pratiques de groupe cr\u00e9ent un sentiment d'appartenance et renforcent nos intentions. On dit qu'une pratique solitaire est comme une \u00e9tincelle, tandis qu'une pratique de groupe est comme un feu qui fait rage. Lorsque nous pratiquons ensemble, nous b\u00e9n\u00e9ficions du soutien du groupe pour rendre notre pratique plus cibl\u00e9e, plus intensive et plus profonde. Les effets positifs de notre pratique se propagent comme des ondulations sur l'eau, alors contribuons \u00e0 la paix dans le monde en pratiquant ensemble !<br \/>\n\u00c0 la fin de la pratique du Bouddha de la m\u00e9decine, nous d\u00e9dions l'\u00e9nergie positive que nous avons cr\u00e9\u00e9e en pratiquant la pratique au bien-\u00eatre de tous les \u00eatres sensibles. Nous prions et d\u00e9dions \u00e9galement pour les individus - pour les malades, les mourants, les morts, et pour le succ\u00e8s dans les activit\u00e9s.<br \/>\nN'h\u00e9sitez pas \u00e0 envoyer vos d\u00e9dicaces \u00e0 spc@yeshinnorbu.se.<br \/>\nBienvenue !<br \/>\nVotre professeur<br \/>\nLa v\u00e9n\u00e9rable Khadro apporte ses nombreuses ann\u00e9es d'exp\u00e9rience dans l'enseignement de la philosophie bouddhiste et de la m\u00e9ditation dans la tradition de Sa Saintet\u00e9 le Dala\u00ef-Lama. Son approche claire et pratique rend les concepts bouddhistes profonds accessibles aux \u00e9tudiants modernes.<\/p>","protected":false},"excerpt":{"rendered":"<p>Join us for Medicine Buddha Puja together, a great way to promote healing for ourselves and others. This practice is falls under the 15 day&#8217;s of Miracles,<\/p>","protected":false},"author":2,"featured_media":548,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[59],"class_list":["post-543","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-ritual","cat_ritual"],"_links":{"self":[{"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/tribe_events\/543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":1,"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/tribe_events\/543\/revisions"}],"predecessor-version":[{"id":1101,"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/tribe_events\/543\/revisions\/1101"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/media\/548"}],"wp:attachment":[{"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/media?parent=543"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/tags?post=543"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/tribe_events_cat?post=543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}