{"id":486,"date":"2025-03-25T07:37:14","date_gmt":"2025-03-25T07:37:14","guid":{"rendered":"https:\/\/lotus.fpmt.org\/event\/events-for-february-2025-jamyang-london-buddhist-centre-20\/"},"modified":"2025-04-01T08:46:49","modified_gmt":"2025-04-01T08:46:49","slug":"events-for-february-2025-jamyang-london-buddhist-centre-20","status":"publish","type":"tribe_events","link":"https:\/\/lotus.fpmt.org\/fr\/event\/events-for-february-2025-jamyang-london-buddhist-centre-20\/","title":{"rendered":"\u00c9v\u00e9nements pour f\u00e9vrier 2025 - Jamyang London Buddhist Centre"},"content":{"rendered":"<p>\u00c9v\u00e9nements pour f\u00e9vrier 2025 - Jamyang London Buddhist CentreCette session r\u00e9guli\u00e8re permet aux \u00e9tudiants de pratiquer diverses m\u00e9ditations bouddhistes avec leurs pairs. Elle est suivie d'un groupe de discussion pour tous ceux qui s'int\u00e9ressent \u00e0 la vision du monde et au mode de vie bouddhistes.<br \/>\nCe groupe informel se r\u00e9unit le mardi soir pour m\u00e9diter et discuter de la pratique bouddhiste. Il offre l'occasion de cr\u00e9er une communaut\u00e9 enrichissante avec des personnes qui s'int\u00e9ressent \u00e0 la pratique et \u00e0 la pleine conscience. Les personnes de tous niveaux d'exp\u00e9rience sont les bienvenues.<br \/>\nM\u00e9ditation libre + groupe de discussion<br \/>\nEn personne uniquement<br \/>\nM\u00e9ditation guid\u00e9e par des pairs<br \/>\nLes dons sont les bienvenus.<br \/>\nCalendrier<br \/>\n18h30-19h00 S\u00e9ance de m\u00e9ditation<br \/>\n19h00-20h00 Groupe de discussion<br \/>\nS\u00e9ance de m\u00e9ditation : \u00e0 quoi puis-je m'attendre ?<br \/>\nS\u00e9ances r\u00e9guli\u00e8res de m\u00e9ditation sans rendez-vous.<br \/>\nUne courte s\u00e9ance de m\u00e9ditation guid\u00e9e anim\u00e9e par divers \u00e9tudiants du Centre bouddhiste Jamyang de Londres, afin de pratiquer diff\u00e9rentes m\u00e9ditations bouddhistes avec leurs pairs.<br \/>\nGroupe de discussion : \u00c0 quoi puis-je m'attendre ?<br \/>\nConversation d\u00e9tendue sur divers sujets li\u00e9s \u00e0 la philosophie bouddhiste, \u00e0 la psychologie bouddhiste et \u00e0 la pratique bouddhiste, autour d'un rafra\u00eechissement.<br \/>\nLa m\u00e9ditation est suivie d'une discussion de groupe sur le bouddhisme, sans ordre du jour, objectifs ou th\u00e8mes pr\u00e9cis, afin d'\u00e9changer des id\u00e9es et des r\u00e9flexions sur les enseignements bouddhistes dans une ambiance d\u00e9tendue, informelle et conviviale.<br \/>\nTout le monde est le bienvenu, que vous soyez un \u00e9tudiant exp\u00e9riment\u00e9 ou un novice en mati\u00e8re de bouddhisme.<br \/>\nComment puis-je m'inscrire ?<br \/>\nR\u00e9servez sur Eventbrite<br \/>\nNous vous sugg\u00e9rons de r\u00e9server votre place \u00e0 l'avance afin d'aider l'animateur \u00e0 organiser l'\u00e9v\u00e9nement. Vous pouvez \u00e9galement vous pr\u00e9senter sans r\u00e9servation.<br \/>\nVeuillez arriver \u00e0 18h20 pour un d\u00e9but \u00e0 18h30.<br \/>\nLes dons sont les bienvenus : Jamyang d\u00e9pend des dons g\u00e9n\u00e9reux des personnes qui participent aux activit\u00e9s du centre. Ces fonds nous permettent d'offrir ce type de cours r\u00e9guli\u00e8rement. Nous vous remercions pour votre g\u00e9n\u00e9rosit\u00e9.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00c9v\u00e9nements pour f\u00e9vrier 2025 - Jamyang London Buddhist CentreCette session r\u00e9guli\u00e8re permet aux \u00e9tudiants de pratiquer diverses m\u00e9ditations bouddhistes avec leurs pairs, suivies d'une...<\/p>","protected":false},"author":2,"featured_media":439,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[4,5],"class_list":["post-486","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-buddhism","tribe_events_cat-meditation","cat_buddhism","cat_meditation"],"_links":{"self":[{"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/tribe_events\/486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":1,"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/tribe_events\/486\/revisions"}],"predecessor-version":[{"id":941,"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/tribe_events\/486\/revisions\/941"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/media\/439"}],"wp:attachment":[{"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/media?parent=486"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/tags?post=486"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/tribe_events_cat?post=486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}