{"id":473,"date":"2025-03-25T07:37:00","date_gmt":"2025-03-25T07:37:00","guid":{"rendered":"https:\/\/lotus.fpmt.org\/event\/exploring-death-and-finding-life-2-workshops-with-bruno-rizzi-foundation-for-developing-compassion-and-wisdom-2\/"},"modified":"2025-04-06T04:15:05","modified_gmt":"2025-04-06T04:15:05","slug":"exploring-death-and-finding-life-2-workshops-with-bruno-rizzi-foundation-for-developing-compassion-and-wisdom-2","status":"publish","type":"tribe_events","link":"https:\/\/lotus.fpmt.org\/fr\/event\/exploring-death-and-finding-life-2-workshops-with-bruno-rizzi-foundation-for-developing-compassion-and-wisdom-2\/","title":{"rendered":"Explorer la mort et trouver la vie - 2 ateliers avec Bruno Rizzi - Fondation pour le d\u00e9veloppement de la compassion et de la sagesse"},"content":{"rendered":"<p>Explorer la mort et trouver la vie - 2 ateliers avec Bruno Rizzi\u00ab Tous les \u00e9v\u00e9nements<br \/>\nCet \u00e9v\u00e9nement est termin\u00e9.<br \/>\n22 f\u00e9vrier @ 10:30 - 18:30 CET<br \/>\n\u00a375<br \/>\nLa vie et la mort ne sont pas distinctes, elles sont profond\u00e9ment li\u00e9es. Ce qui nourrit l'une soutient in\u00e9vitablement l'autre.<br \/>\nA propos des ateliers<br \/>\nCette s\u00e9rie d'ateliers vous invite \u00e0 explorer la profonde sagesse de la tradition bouddhiste tib\u00e9taine dans l'approche de la mort et de l'impermanence, int\u00e9gr\u00e9e aux connaissances pratiques des soins palliatifs. Ensemble, nous ferons face \u00e0 l'impermanence de la vie avec courage et clart\u00e9, ouvrant ainsi des opportunit\u00e9s de croissance, de joie et de sens.<br \/>\nPourquoi ces ateliers ?<br \/>\nSe pr\u00e9parer \u00e0 la mort commence par accepter la vie telle qu'elle est r\u00e9ellement, sans illusions, sans romantisme ni peur. En prenant conscience de la dynamique de nos projections, de nos espoirs et de nos angoisses, nous pouvons vivre plus pleinement le pr\u00e9sent et aborder la fin de la vie avec paix et dignit\u00e9.<br \/>\nGr\u00e2ce \u00e0 cette exploration, nous pouvons transformer notre relation avec la mort et, par cons\u00e9quent, transformer notre fa\u00e7on de vivre au quotidien.<br \/>\nCe que vous apprendrez :<br \/>\nUne compr\u00e9hension plus profonde de la mort et de l'impermanence \u00e0 travers le prisme des enseignements bouddhistes tib\u00e9tains.<br \/>\nPerspectives issues des pratiques en soins palliatifs pour soutenir les personnes en fin de vie et renforcer la pr\u00e9sence compatissante.<br \/>\nDes outils pratiques pour cultiver la conscience, la pr\u00e9sence et la connexion dans votre vie quotidienne.<br \/>\nStructure de l'atelier<br \/>\nCe voyage se d\u00e9roulera en 4 sessions sur 2 week-ends distincts en janvier et f\u00e9vrier, tous deux organis\u00e9s dans un espace de groupe partag\u00e9 :<br \/>\n25 et 26 janvier : En personne \u00e0 Nagarjuna Granada et en ligne \u00e0 Nagarjuna Barcelona<br \/>\n22 et 23 f\u00e9vrier : En personne \u00e0 Nagarjuna Barcelona et en ligne \u00e0 Nagarjuna Granada<br \/>\nLes sessions seront exp\u00e9rientielles, combinant enseignements, pratiques m\u00e9ditatives et discussions de groupe afin d'assurer une exp\u00e9rience de soutien et de transformation.<br \/>\nQui devrait participer ?<br \/>\nCes ateliers sont ouverts \u00e0 toute personne d\u00e9sireuse d'explorer les th\u00e8mes de la vie, de la mort et de l'impermanence, que ce soit \u00e0 des fins de d\u00e9veloppement personnel, de d\u00e9veloppement spirituel ou de pratique professionnelle dans le cadre d'un r\u00f4le d'aidant.<br \/>\nLangue<br \/>\nLes sessions seront propos\u00e9es en anglais avec traduction en espagnol.<br \/>\nR\u00e9servations<br \/>\nLes places sont limit\u00e9es afin de garantir la s\u00e9curit\u00e9 et l'intimit\u00e9 du groupe.<br \/>\n\u27a1\ufe0f Pour r\u00e9server votre place, veuillez consulter le site web de Nagarjuna Granada.<br \/>\nNous vous encourageons \u00e0 r\u00e9server t\u00f4t afin de garantir votre place dans cette exploration enrichissante.<br \/>\nRejoignez-nous dans ce voyage de r\u00e9flexion profonde et de transformation. Ensemble, nous explorerons comment vivre \u2013 et mourir \u2013 avec plus de conscience, de compassion et de paix.<br \/>\n\u201c La mort en soi n'est pas effrayante, c'est notre esprit qui la rend terrifiante. \u201d<br \/>\n- Lama Zopa Rinpoch\u00e9 -<br \/>\nAnimateur - Bruno Rizzi -<br \/>\nBruno pratique le bouddhisme depuis 1980, ann\u00e9e o\u00f9 il a rencontr\u00e9 le v\u00e9n\u00e9rable Lama Thubten Yeshe et Lama Zopa Rinpoch\u00e9 en Italie. Il a v\u00e9cu comme moine ordonn\u00e9 pendant sept ans, \u00e9tudiant au monast\u00e8re de Nalanda en France, ainsi qu'en Inde et au N\u00e9pal.<br \/>\nDepuis 22 ans, il travaille comme infirmier en soins palliatifs \u00e0 l'hospice Christophorus de Munich, en Allemagne. Depuis 15 ans, il anime des ateliers et des retraites sur le th\u00e8me \u201c Affronter la mort, trouver un sens \u00e0 la vie \u201d.\u201d<br \/>\nIl est facilitateur agr\u00e9\u00e9 des 16 lignes directrices et collabore avec Universal Education \u2013 FDCW (Fondation pour le d\u00e9veloppement de la compassion et de la sagesse).<\/p>","protected":false},"excerpt":{"rendered":"<p>Rejoignez Bruno Rizzi dans cette s\u00e9rie d'ateliers transformateurs pour explorer la mort non pas comme une fin, mais comme une opportunit\u00e9 d'embrasser la vie avec plus de clart\u00e9, de compassion et de sens. Que vous soyez \u00e0 la recherche d'un d\u00e9veloppement personnel ou d'un aper\u00e7u professionnel, ce voyage vous permettra d'\u00eatre mieux pr\u00e9par\u00e9 \u00e0 affronter les transitions de la vie avec ouverture et s\u00e9r\u00e9nit\u00e9.<\/p>","protected":false},"author":2,"featured_media":414,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[58],"class_list":["post-473","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-secular-ethics","cat_secular-ethics"],"_links":{"self":[{"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/tribe_events\/473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":1,"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/tribe_events\/473\/revisions"}],"predecessor-version":[{"id":1117,"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/tribe_events\/473\/revisions\/1117"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/media\/414"}],"wp:attachment":[{"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/media?parent=473"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/tags?post=473"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/lotus.fpmt.org\/fr\/wp-json\/wp\/v2\/tribe_events_cat?post=473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}